{"id":1208,"date":"2007-07-15T01:53:10","date_gmt":"2007-07-15T01:53:10","guid":{"rendered":"https:\/\/dialogos.ca\/?p=1208"},"modified":"2012-08-24T01:58:13","modified_gmt":"2012-08-24T01:58:13","slug":"teresa-leon","status":"publish","type":"post","link":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/","title":{"rendered":"Teresa Le\u00f3n"},"content":{"rendered":"<p><strong>Cantos lejanos<\/strong><\/p>\n<p><em>Poeta <strong>Teresa Le\u00f3n<\/strong> naci\u00f3 en la ciudad porte\u00f1a de Valpara\u00edso, Chile, en 1940. Lleg\u00f3 a Canad\u00e1 en 1975, y ha vivido en Toronto desde 1983. Despu\u00e9s de muchos a\u00f1os de escribir poes\u00eda, en estos momentos su nueva expresi\u00f3n es pintar y dibujar. Tambi\u00e9n es madre de siete ni\u00f1os y abuela de 15 nietos, y es miembro fundador de Creando Puentes, empresa dedicada a promover los intereses de las mujeres hisp\u00e1nicas en Toronto. El poema aqu\u00ed originalmente fue publicado sin t\u00edtulo en su colecci\u00f3n <strong>Poes\u00eda Errante<\/strong>, y aparece con el permiso de su hija Irma Paredes.<\/em><\/p>\n<p><!--more--><\/p>\n<p>Cantos lejanos de gaviotas,<br \/>\nCantos tristes augurios de lluvia,<br \/>\nNeblina densa fuerte como mi<br \/>\nmisma mente.<br \/>\nDolor profundo a\u00f1oranza,<br \/>\nSonido de buey porte\u00f1o,<br \/>\nQue callas mi alma lejana.<br \/>\nEs la lluvia que viene a lavar<br \/>\nEl dolor<\/p>\n<p><a href=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1209\" title=\"Cantos lejanos\" src=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg\" alt=\"\" width=\"231\" height=\"218\" \/><\/a>Es la frescura que deja, es volver<br \/>\nA nacer<\/p>\n<p>Es sentir el fr\u00edo que atraviesa tus huesos<br \/>\nPero es la vida misma que vuelve<br \/>\nA nacer<\/p>\n<p>Es s\u00f3lo mi mente mi alma,<br \/>\nPor qu\u00e9 mi cuerpo no te siente,<br \/>\nNo se moja no se trasmina.<br \/>\nEs cuerpo viejo l\u00e1nguido<br \/>\nQue no quiere vivir<br \/>\nPero mi alma porte\u00f1a le canta,<br \/>\nLo mece, lo arrulla<br \/>\nY le dice dame tu mano,<br \/>\nCanta, dame tu mano<br \/>\ny saltaremos de pelda\u00f1o<br \/>\nA pelda\u00f1o<br \/>\nDe cerro a cerro<br \/>\nEntre gritos de chiquillos,<br \/>\nSortearemos la bajada<br \/>\nAl mirar la ventana<br \/>\nDe mi vida<br \/>\ncon paisajes extra\u00f1os<br \/>\nDonde no hay gritos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cantos lejanos Poeta Teresa Le\u00f3n naci\u00f3 en la ciudad porte\u00f1a de Valpara\u00edso, Chile, en 1940. Lleg\u00f3 a Canad\u00e1 en 1975, y ha vivido en Toronto desde 1983. Despu\u00e9s de muchos a\u00f1os de escribir poes\u00eda, en estos momentos su nueva expresi\u00f3n &hellip; <a href=\"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-1208","post","type-post","status-publish","format-standard","hentry","category-lit-hispana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teresa Le\u00f3n - Di\u00e1logos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teresa Le\u00f3n - Di\u00e1logos\" \/>\n<meta property=\"og:description\" content=\"Cantos lejanos Poeta Teresa Le\u00f3n naci\u00f3 en la ciudad porte\u00f1a de Valpara\u00edso, Chile, en 1940. Lleg\u00f3 a Canad\u00e1 en 1975, y ha vivido en Toronto desde 1983. Despu\u00e9s de muchos a\u00f1os de escribir poes\u00eda, en estos momentos su nueva expresi\u00f3n &hellip; Sigue leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1logos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DialogosInterculturalServices\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-15T01:53:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-08-24T01:58:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg\" \/>\n<meta name=\"author\" content=\"di\u00e1logos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"di\u00e1logos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/\"},\"author\":{\"name\":\"di\u00e1logos\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/person\\\/ee54b54565eded729000f79f6b337905\"},\"headline\":\"Teresa Le\u00f3n\",\"datePublished\":\"2007-07-15T01:53:10+00:00\",\"dateModified\":\"2012-08-24T01:58:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/Cantos-lejanos.jpg\",\"articleSection\":[\"Literatura hispana\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/\",\"name\":\"Teresa Le\u00f3n - Di\u00e1logos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/Cantos-lejanos.jpg\",\"datePublished\":\"2007-07-15T01:53:10+00:00\",\"dateModified\":\"2012-08-24T01:58:13+00:00\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2007\\\/07\\\/teresa-leon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/Cantos-lejanos.jpg\",\"contentUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/Cantos-lejanos.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#website\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/\",\"name\":\"Di\u00e1logos\",\"description\":\"Intercultural Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dialogos.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\",\"name\":\"Di\u00e1logos Intercultural Services\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Dialogos.png\",\"contentUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Dialogos.png\",\"width\":340,\"height\":95,\"caption\":\"Di\u00e1logos Intercultural Services\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DialogosInterculturalServices\",\"https:\\\/\\\/x.com\\\/DialogosTrans\",\"https:\\\/\\\/ca.linkedin.com\\\/pub\\\/martin-boyd\\\/3\\\/b7a\\\/b94\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/person\\\/ee54b54565eded729000f79f6b337905\",\"name\":\"di\u00e1logos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"caption\":\"di\u00e1logos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teresa Le\u00f3n - Di\u00e1logos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/","og_locale":"es_ES","og_type":"article","og_title":"Teresa Le\u00f3n - Di\u00e1logos","og_description":"Cantos lejanos Poeta Teresa Le\u00f3n naci\u00f3 en la ciudad porte\u00f1a de Valpara\u00edso, Chile, en 1940. Lleg\u00f3 a Canad\u00e1 en 1975, y ha vivido en Toronto desde 1983. Despu\u00e9s de muchos a\u00f1os de escribir poes\u00eda, en estos momentos su nueva expresi\u00f3n &hellip; Sigue leyendo &rarr;","og_url":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/","og_site_name":"Di\u00e1logos","article_publisher":"https:\/\/www.facebook.com\/DialogosInterculturalServices","article_published_time":"2007-07-15T01:53:10+00:00","article_modified_time":"2012-08-24T01:58:13+00:00","og_image":[{"url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg","type":"","width":"","height":""}],"author":"di\u00e1logos","twitter_misc":{"Escrito por":"di\u00e1logos","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/#article","isPartOf":{"@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/"},"author":{"name":"di\u00e1logos","@id":"https:\/\/dialogos.ca\/#\/schema\/person\/ee54b54565eded729000f79f6b337905"},"headline":"Teresa Le\u00f3n","datePublished":"2007-07-15T01:53:10+00:00","dateModified":"2012-08-24T01:58:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/dialogos.ca\/#organization"},"image":{"@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg","articleSection":["Literatura hispana"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/","url":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/","name":"Teresa Le\u00f3n - Di\u00e1logos","isPartOf":{"@id":"https:\/\/dialogos.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/#primaryimage"},"image":{"@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg","datePublished":"2007-07-15T01:53:10+00:00","dateModified":"2012-08-24T01:58:13+00:00","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dialogos.ca\/es\/2007\/07\/teresa-leon\/#primaryimage","url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg","contentUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/08\/Cantos-lejanos.jpg"},{"@type":"WebSite","@id":"https:\/\/dialogos.ca\/#website","url":"https:\/\/dialogos.ca\/","name":"Di\u00e1logos","description":"Intercultural Services","publisher":{"@id":"https:\/\/dialogos.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dialogos.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/dialogos.ca\/#organization","name":"Di\u00e1logos Intercultural Services","url":"https:\/\/dialogos.ca\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dialogos.ca\/#\/schema\/logo\/image\/","url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2016\/12\/Dialogos.png","contentUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2016\/12\/Dialogos.png","width":340,"height":95,"caption":"Di\u00e1logos Intercultural Services"},"image":{"@id":"https:\/\/dialogos.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DialogosInterculturalServices","https:\/\/x.com\/DialogosTrans","https:\/\/ca.linkedin.com\/pub\/martin-boyd\/3\/b7a\/b94"]},{"@type":"Person","@id":"https:\/\/dialogos.ca\/#\/schema\/person\/ee54b54565eded729000f79f6b337905","name":"di\u00e1logos","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","caption":"di\u00e1logos"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p45YGu-ju","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/1208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/comments?post=1208"}],"version-history":[{"count":0,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/1208\/revisions"}],"wp:attachment":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/media?parent=1208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/categories?post=1208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/tags?post=1208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}