{"id":2045,"date":"2012-11-30T15:51:19","date_gmt":"2012-11-30T15:51:19","guid":{"rendered":"https:\/\/dialogos.ca\/?p=2045"},"modified":"2012-11-30T15:51:19","modified_gmt":"2012-11-30T15:51:19","slug":"una-historia-de-esperanza","status":"publish","type":"post","link":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/","title":{"rendered":"Una historia de esperanza"},"content":{"rendered":"<p><em><strong><a href=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1972\" title=\"Papalotero\" src=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg 200w, https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero.jpg 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Papalotero<\/strong><\/em><br \/>\n<strong> Autor: Martin Boyd<\/strong><br \/>\n<strong> Editorial: Editorial Ink<\/strong><br \/>\n<strong> M\u00e9xico, 2012<\/strong><\/p>\n<p><strong>Rese\u00f1a por Brian Kennedy<\/strong><\/p>\n<p>Martin Boyd describe <em>Papalotero<\/em> como una &#8220;<a href=\"https:\/\/dialogos.ca\/cartera\/publications\/?lang=es\">historia de amor intercultural<\/a>&#8220;, y la novela \u00a0ofrece, sin duda, una visi\u00f3n incisiva y a menudo c\u00f3mica de los choques de perspectivas culturales que inevitablemente se producen en las ciudades tan abundantemente multiculturales como Toronto. Pero yo dir\u00eda que el choque de valores que se explora en <em>Papalotero<\/em> es algo a\u00fan m\u00e1s esencial, algo que trasciende las fronteras culturales: un choque entre el deseo humano b\u00e1sico de controlar y regular la vida, y la valent\u00eda para abrazarla, vivirla y amarla plenamente, reconoci\u00e9ndola como el extraordinario accidente, o \u00a0milagro, que es en realidad.<\/p>\n<p><!--more-->La adopci\u00f3n de una perspectiva de la vida tan audaz no es nada f\u00e1cil, sobre todo para la clase media de Am\u00e9rica del Norte, los que estamos acostumbrados a un entorno controlado y estable, donde ponemos \u00a0nuestro empe\u00f1o para hacer que todo sea seguro y predecible. Como ant\u00eddoto a la estabilidad de esta vida, Boyd plantea el concepto del &#8220;papalotero&#8221;; para ello proporciona una definici\u00f3n de diccionario a modo de introducci\u00f3n a la novela: &#8220;Uno de esos raros individuos lo suficientemente valientes como para dedicar su vida a hacer lo que les gusta, sin preocuparse de si la vocaci\u00f3n elegida cuenta con la aprobaci\u00f3n social, un paquete de jubilaci\u00f3n o un plan dental&#8221;.<\/p>\n<p>Teresa Jones, protagonista de la novela, es una joven que se ahoga en un mundo carente de &#8220;papaloteros&#8221;. Auto-proclamada &#8220;zopenca&#8221; en una familia de acad\u00e9micos excesivamente exitosos, Teresa ha luchado toda su vida solo para ser una persona com\u00fan, y ahora, a los 19 a\u00f1os de edad, empieza a sentir que el sistema apesta. A modo de protesta, se ha negado a ir a la universidad y en su lugar y ha tomado un trabajo mundano con salario m\u00ednimo. En realidad, Teresa es demasiado inteligente, puede darle cien vueltas a su hermano Milton, un destacado estudiante de literatura en la \u201c<em>oh-so-prestigious<\/em>\u201d Universidad de Toronto, quien, a pesar de su sapiencia, no puede rivalizar con la agudeza de su hermana. Teresa es muy contreras, de pensamiento lateral, demasiado diferente como para que le quede la camisa de fuerza que su puritana familia parece haber preparado para ella.<\/p>\n<p>Por otro lado, Elena, la mejor amiga de Teresa, ha prosperado en el mismo entorno controlado. Bonita, inteligente y socialmente h\u00e1bil, Elena siempre ha seguido las reglas establecidas por la sociedad, o m\u00e1s concretamente, por su padre ultra-materialista, y siempre con buenos resultados. Sin embargo, cuando la tragedia \u00a0irrumpe de repente en su mundo privado, descubre que no tiene los recursos para enfrentarla.<\/p>\n<p>En estos momentos entra Miguel \u00c1ngel, un curioso joven mexicano que se describe como &#8220;papalotero&#8221;. En una ciudad pr\u00e1ctica y ordenada, una ciudad en auge de banqueros y grandes empresas, \u00bfqu\u00e9 podr\u00eda ser m\u00e1s absurdo que volar papalotes para ganarse la vida? Sin embargo, es a trav\u00e9s del prisma de la perspectiva de Miguel \u00c1ngel, \u00a0que vemos lo absurdo de los otros personajes, cuyas respectivas neurosis reflejan la simple verdad de que la seguridad material no puede garantizar una vida feliz y plena. Los papalotes de Miguel \u00c1ngel, llenando el cielo de Toronto, son un s\u00edmbolo de la alegr\u00eda con la que sale al encuentro de la vida.<\/p>\n<p>Como comedia rom\u00e1ntica posmoderna, <em>Papalotero<\/em> avanza a paso veloz y entretenido, mientras se desarrolla el raro tri\u00e1ngulo de amor entre Teresa, Elena y Miguel \u00c1ngel. La pericia del autor en el uso del di\u00e1logo, \u00a0tan convincentemente real y, al mismo tiempo, intensamente ingenioso, impulsa la historia mientras que los diferentes personajes participan en una serie de justas verbales repletas de r\u00e9plicas mordaces y malentendidos divertidos, pero en \u00faltima instancia desastrosos.<\/p>\n<p>La novela tambi\u00e9n cuenta con los elementos de misterio, ya que el car\u00e1cter enigm\u00e1tico del &#8220;Papalotero&#8221; mantiene a Teresa y a Elena en duda sobre sus intenciones reales. \u00bfPuede realmente ser un papalotero profesional? \u00bfO acaso solo se trata de un despliegue fingido? \u00bfC\u00f3mo es que parece saber tanto acerca de ellas? \u00bfEs ps\u00edquico? \u00bfO simplemente es un psic\u00f3pata? Por alocadas que sean sus hip\u00f3tesis, no hay forma alguna de que adivinen la verdad acerca del misterioso mexicano, cuya misma existencia es de por s\u00ed, un milagro.<\/p>\n<p>La trama da algunos giros sorprendentes, no obstante, la coherente voz narrativa de Boyd entreteje los distintos cabos con una fluidez notable. Su h\u00e1bil forma de cambiar las perspectivas narrativas entre los personajes, una estrategia posmoderna que a veces puede resultar inquietante, funciona muy bien en este caso, sobre todo en una novela que satiriza de manera tan aguda las enormes brechas entre las distintas perspectivas individuales del mismo problema. En cierto sentido, estas diferencias son de \u00edndole cultural, como el origen mexicano de Miguel \u00c1ngel, elemento fundamental de su visi\u00f3n de la vida, tan diferente de la &#8220;\u00e9tica protestante del trabajo&#8221; de la familia de Teresa, o la parecida &#8220;estoica creencia eslava en la importancia del trabajo arduo&#8221; del padre de Elena. Pero tal como se muestra en la novela, dichos estereotipos culturales no son definitivos y cualquier persona, en cualquier lugar, puede elegir ser un &#8220;papalotero&#8221;; no es f\u00e1cil, pero s\u00ed posible.<\/p>\n<p>\u00bfUna historia de amor intercultural? \u00bfUna s\u00e1tira? \u00bfUn misterio? \u00bfComentario social? Todas las anteriores. Pero, sobre todo, una historia de esperanza.<\/p>\n<p><em>Esta rese\u00f1a se public\u00f3 originalmente en ingl\u00e9s en Amazon Book Reviews y se reproduce aqu\u00ed con el permiso del autor.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papalotero Autor: Martin Boyd Editorial: Editorial Ink M\u00e9xico, 2012 Rese\u00f1a por Brian Kennedy Martin Boyd describe Papalotero como una &#8220;historia de amor intercultural&#8220;, y la novela \u00a0ofrece, sin duda, una visi\u00f3n incisiva y a menudo c\u00f3mica de los choques de &hellip; <a href=\"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2045","post","type-post","status-publish","format-standard","hentry","category-resenas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una historia de esperanza - Di\u00e1logos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una historia de esperanza - Di\u00e1logos\" \/>\n<meta property=\"og:description\" content=\"Papalotero Autor: Martin Boyd Editorial: Editorial Ink M\u00e9xico, 2012 Rese\u00f1a por Brian Kennedy Martin Boyd describe Papalotero como una &#8220;historia de amor intercultural&#8220;, y la novela \u00a0ofrece, sin duda, una visi\u00f3n incisiva y a menudo c\u00f3mica de los choques de &hellip; Sigue leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1logos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DialogosInterculturalServices\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-30T15:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg\" \/>\n<meta name=\"author\" content=\"di\u00e1logos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"di\u00e1logos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/\"},\"author\":{\"name\":\"di\u00e1logos\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/person\\\/ee54b54565eded729000f79f6b337905\"},\"headline\":\"Una historia de esperanza\",\"datePublished\":\"2012-11-30T15:51:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/\"},\"wordCount\":944,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Papalotero-200x300.jpg\",\"articleSection\":[\"Rese\u00f1as\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/\",\"name\":\"Una historia de esperanza - Di\u00e1logos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Papalotero-200x300.jpg\",\"datePublished\":\"2012-11-30T15:51:19+00:00\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2012\\\/11\\\/una-historia-de-esperanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Papalotero-200x300.jpg\",\"contentUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Papalotero-200x300.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#website\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/\",\"name\":\"Di\u00e1logos\",\"description\":\"Intercultural Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dialogos.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\",\"name\":\"Di\u00e1logos Intercultural Services\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Dialogos.png\",\"contentUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Dialogos.png\",\"width\":340,\"height\":95,\"caption\":\"Di\u00e1logos Intercultural Services\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DialogosInterculturalServices\",\"https:\\\/\\\/x.com\\\/DialogosTrans\",\"https:\\\/\\\/ca.linkedin.com\\\/pub\\\/martin-boyd\\\/3\\\/b7a\\\/b94\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/person\\\/ee54b54565eded729000f79f6b337905\",\"name\":\"di\u00e1logos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"caption\":\"di\u00e1logos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una historia de esperanza - Di\u00e1logos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/","og_locale":"es_ES","og_type":"article","og_title":"Una historia de esperanza - Di\u00e1logos","og_description":"Papalotero Autor: Martin Boyd Editorial: Editorial Ink M\u00e9xico, 2012 Rese\u00f1a por Brian Kennedy Martin Boyd describe Papalotero como una &#8220;historia de amor intercultural&#8220;, y la novela \u00a0ofrece, sin duda, una visi\u00f3n incisiva y a menudo c\u00f3mica de los choques de &hellip; Sigue leyendo &rarr;","og_url":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/","og_site_name":"Di\u00e1logos","article_publisher":"https:\/\/www.facebook.com\/DialogosInterculturalServices","article_published_time":"2012-11-30T15:51:19+00:00","og_image":[{"url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg","type":"","width":"","height":""}],"author":"di\u00e1logos","twitter_misc":{"Escrito por":"di\u00e1logos","Tiempo de lectura":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/#article","isPartOf":{"@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/"},"author":{"name":"di\u00e1logos","@id":"https:\/\/dialogos.ca\/#\/schema\/person\/ee54b54565eded729000f79f6b337905"},"headline":"Una historia de esperanza","datePublished":"2012-11-30T15:51:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/"},"wordCount":944,"commentCount":0,"publisher":{"@id":"https:\/\/dialogos.ca\/#organization"},"image":{"@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg","articleSection":["Rese\u00f1as"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/","url":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/","name":"Una historia de esperanza - Di\u00e1logos","isPartOf":{"@id":"https:\/\/dialogos.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/#primaryimage"},"image":{"@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg","datePublished":"2012-11-30T15:51:19+00:00","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dialogos.ca\/es\/2012\/11\/una-historia-de-esperanza\/#primaryimage","url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg","contentUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2012\/11\/Papalotero-200x300.jpg"},{"@type":"WebSite","@id":"https:\/\/dialogos.ca\/#website","url":"https:\/\/dialogos.ca\/","name":"Di\u00e1logos","description":"Intercultural Services","publisher":{"@id":"https:\/\/dialogos.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dialogos.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/dialogos.ca\/#organization","name":"Di\u00e1logos Intercultural Services","url":"https:\/\/dialogos.ca\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dialogos.ca\/#\/schema\/logo\/image\/","url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2016\/12\/Dialogos.png","contentUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2016\/12\/Dialogos.png","width":340,"height":95,"caption":"Di\u00e1logos Intercultural Services"},"image":{"@id":"https:\/\/dialogos.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DialogosInterculturalServices","https:\/\/x.com\/DialogosTrans","https:\/\/ca.linkedin.com\/pub\/martin-boyd\/3\/b7a\/b94"]},{"@type":"Person","@id":"https:\/\/dialogos.ca\/#\/schema\/person\/ee54b54565eded729000f79f6b337905","name":"di\u00e1logos","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","caption":"di\u00e1logos"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p45YGu-wZ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/2045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/comments?post=2045"}],"version-history":[{"count":0,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/2045\/revisions"}],"wp:attachment":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/media?parent=2045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/categories?post=2045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/tags?post=2045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}