{"id":2869,"date":"2013-12-06T19:30:25","date_gmt":"2013-12-06T19:30:25","guid":{"rendered":"https:\/\/dialogos.ca\/?p=2869"},"modified":"2026-04-02T16:34:58","modified_gmt":"2026-04-02T16:34:58","slug":"chavela-vargas-una-voz-del-mas-alla","status":"publish","type":"post","link":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/","title":{"rendered":"Chavela Vargas, una voz del m\u00e1s all\u00e1"},"content":{"rendered":"<p><strong>Martin Boyd<\/strong><\/p>\n<p><a href=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2867\" src=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg\" alt=\"Chavela Vargas\" width=\"241\" height=\"300\" srcset=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg 241w, https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas.jpeg 386w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/a>Chavela Vargas, la cantante mexicana con voz incomparable que parece encarnar el esp\u00edritu mismo de la melancol\u00eda, nos dej\u00f3 el a\u00f1o pasado tras una carrera musical de m\u00e1s de 60 a\u00f1os que la convirti\u00f3 en una de las figuras m\u00e1s importantes de la cultura mexicana contempor\u00e1nea y la aut\u00e9ntica encarnaci\u00f3n de \u201c<a title=\"Video de &quot;La Llorona&quot; \" href=\"http:\/\/www.youtube.com\/watch?v=0gQ31m4Yt0s\" target=\"_blank\" rel=\"noopener\">La Llorona<\/a>\u201d, el tema que lleg\u00f3 a ser su canci\u00f3n signatura.<\/p>\n<p><!--more--><\/p>\n<p>Aunque conocida en todo el mundo como mexicana, de hecho Vargas naci\u00f3 en Costa Rica en 1919 y fue nacionalizada mexicana muchos a\u00f1os despu\u00e9s. Empez\u00f3 a cantar en Costa Rica, antes de que emigrara sola a M\u00e9xico a los 14 a\u00f1os de edad, huyendo de un pa\u00eds que no supo, seg\u00fan ella, valorar su talento.<\/p>\n<p>En M\u00e9xico desempe\u00f1\u00f3 varios oficios hasta que apareci\u00f3 la oportunidad que la hizo tropezarse con la fama: el tema &#8220;Macorina&#8221;, una canci\u00f3n de rebeld\u00eda del siglo XVII que interpret\u00f3 con sus propios arreglos. Chavela Vargas sorprendi\u00f3 por su actitud desafiante y su apuesta radical. Eran \u00e9pocas en las que paseaba con el cantante mexicano <a title=\"Agust\u00edn Lara\" href=\"http:\/\/es.wikipedia.org\/wiki\/Agust%C3%ADn_Lara\" target=\"_blank\" rel=\"noopener\">Agust\u00edn Lara<\/a>, era musa y amiga del gran escritor <a title=\"Juan Rulfo\" href=\"https:\/\/dialogos.ca\/es\/2013\/11\/la-traduccion-de-america-latina-cuarta-parte-el-realismo-magico\/\" target=\"_blank\" rel=\"noopener\">Juan Rulfo<\/a>, y viv\u00eda con los pintores m\u00edticos <a title=\"Sitio web de Diego Rivera\" href=\"http:\/\/www.diegorivera.org\/\" target=\"_blank\" rel=\"noopener\">Diego Rivera<\/a> y <a title=\"Fans de Frida Kahlo\" href=\"http:\/\/www.fridakahlofans.com\/\" target=\"_blank\" rel=\"noopener\">Frida Kahlo<\/a>. Entre sus canciones m\u00e1s famosas destacan &#8220;La Llorona&#8221;, &#8220;Somos&#8221;, &#8220;Luz de luna&#8221; o &#8220;Canci\u00f3n de las simples cosas&#8221;. Vargas grab\u00f3 m\u00e1s de 40 discos -entre propios y ajenos, para los que prest\u00f3 la gravedad de su voz- y protagoniz\u00f3 casi mil conciertos.<\/p>\n<p>Tras varios a\u00f1os de lucha con el alcoholismo, Chavela Vargas volvi\u00f3 a cantar a principios de los noventa. Manolo Arroyo la redescubri\u00f3 en El H\u00e1bito, en la colonia de Coyoac\u00e1n en el Distrito Federal, donde cantaba, y la llev\u00f3 a Espa\u00f1a. El cineasta espa\u00f1ol <a title=\"Todo Pedro Almod\u00f3var\" href=\"http:\/\/todopedroalmodovar.blogspot.ca\/\" target=\"_blank\" rel=\"noopener\">Pedro Almod\u00f3var<\/a> le ofreci\u00f3 participar en su producci\u00f3n La flor de mi secreto. <a title=\"Sitio web de Joaqu\u00edn Sabina\" href=\"http:\/\/www.jsabina.com\/home\" target=\"_blank\" rel=\"noopener\">Joaqu\u00edn Sabina<\/a> \u2013uno de los cantautores espa\u00f1oles m\u00e1s destacados de las \u00faltimos tres d\u00e9cadas\u2013 la invit\u00f3 a cantar en varios de sus discos. Su fama en Espa\u00f1a lleg\u00f3 a tanto que una calle de Burgos lleva su nombre. Para Chavela, Espa\u00f1a era &#8220;un pa\u00eds que me hizo su amiga en los a\u00f1os 80, abri\u00e9ndome sus brazos y su juventud&#8221;. Almod\u00f3var bes\u00f3 el suelo del escenario del Pabell\u00f3n de Deportes del Real Madrid y pidi\u00f3 silencio a la audiencia antes de entregar a Vargas el Premio Latino de Honor. El Consejo de Ministros espa\u00f1ol le concedi\u00f3 la Gran Cruz de Isabel la Cat\u00f3lica en el a\u00f1o 2000.<\/p>\n<p>Tras cumplir medio siglo de carrera art\u00edstica, la cantante mexicana se despidi\u00f3 de los escenarios en octubre de 2006 con un concierto homenaje en la Ciudad de M\u00e9xico. &#8220;No quiero que me vayan a ver solamente por ser una viejita simp\u00e1tica&#8221;, dijo. Sin embargo, sigui\u00f3 colaborando en grabaciones junto a otros artistas como <a title=\"Miguel Bos\u00e9\" href=\"http:\/\/es.wikipedia.org\/wiki\/Miguel_Bos%C3%A9\" target=\"_blank\" rel=\"noopener\">Miguel Bos\u00e9<\/a>, Joaqu\u00edn Sabina, <a title=\"Ana Bel\u00e9n\" href=\"http:\/\/es.wikipedia.org\/wiki\/Ana_Bel%C3%A9n\" target=\"_blank\" rel=\"noopener\">Ana Bel\u00e9n<\/a> y <a title=\"Armando Manzanero\" href=\"http:\/\/es.wikipedia.org\/wiki\/Armando_Manzanero\" target=\"_blank\" rel=\"noopener\">Armando Manzanero<\/a>.<\/p>\n<p>Durante 2009, con motivo de su 90 aniversario, el Gobierno de la Ciudad de M\u00e9xico le rindi\u00f3 un homenaje nombr\u00e1ndola ciudadana distinguida. Una mujer diminuta pero pose\u00edda de gran fuerza, Vargas siempre se rebel\u00f3 contra los paradigmas tradicionales que delimitaban la definici\u00f3n de la mujer. En 2001 le dijo al diario espa\u00f1ol <em>El Pa\u00eds:<\/em> \u201cYo he tenido que luchar para ser yo y que se me respete, y llevar ese estigma, para m\u00ed es un orgullo. Llevar el nombre de lesbiana. No lo voy presumiendo, no lo voy pregonando, pero no lo niego&#8221;.<\/p>\n<p>Chavela Vargas falleci\u00f3 en Cuernavaca, Morelos, M\u00e9xico, el 5 de agosto de 2012. En sus discos su voz extraordinaria resuena, con su timbre de \u00e1ngel harapiento, como una voz del m\u00e1s all\u00e1, rebelde, casi m\u00edstica, y finalmente libre de los dolores y angustias de los cuales nos canta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martin Boyd Chavela Vargas, la cantante mexicana con voz incomparable que parece encarnar el esp\u00edritu mismo de la melancol\u00eda, nos dej\u00f3 el a\u00f1o pasado tras una carrera musical de m\u00e1s de 60 a\u00f1os que la convirti\u00f3 en una de las &hellip; <a href=\"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-2869","post","type-post","status-publish","format-standard","hentry","category-cultura-y-sociedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chavela Vargas, una voz del m\u00e1s all\u00e1 - Di\u00e1logos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chavela Vargas, una voz del m\u00e1s all\u00e1 - Di\u00e1logos\" \/>\n<meta property=\"og:description\" content=\"Martin Boyd Chavela Vargas, la cantante mexicana con voz incomparable que parece encarnar el esp\u00edritu mismo de la melancol\u00eda, nos dej\u00f3 el a\u00f1o pasado tras una carrera musical de m\u00e1s de 60 a\u00f1os que la convirti\u00f3 en una de las &hellip; Sigue leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/\" \/>\n<meta property=\"og:site_name\" content=\"Di\u00e1logos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DialogosInterculturalServices\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-06T19:30:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-02T16:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"386\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"di\u00e1logos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"di\u00e1logos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/\"},\"author\":{\"name\":\"di\u00e1logos\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/person\\\/ee54b54565eded729000f79f6b337905\"},\"headline\":\"Chavela Vargas, una voz del m\u00e1s all\u00e1\",\"datePublished\":\"2013-12-06T19:30:25+00:00\",\"dateModified\":\"2026-04-02T16:34:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/\"},\"wordCount\":659,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/Chavela-Vargas-241x300.jpeg\",\"articleSection\":[\"Cultura y sociedad\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/\",\"name\":\"Chavela Vargas, una voz del m\u00e1s all\u00e1 - Di\u00e1logos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/Chavela-Vargas-241x300.jpeg\",\"datePublished\":\"2013-12-06T19:30:25+00:00\",\"dateModified\":\"2026-04-02T16:34:58+00:00\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/es\\\/2013\\\/12\\\/chavela-vargas-una-voz-del-mas-alla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/Chavela-Vargas-241x300.jpeg\",\"contentUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/Chavela-Vargas-241x300.jpeg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#website\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/\",\"name\":\"Di\u00e1logos\",\"description\":\"Intercultural Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dialogos.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#organization\",\"name\":\"Di\u00e1logos Intercultural Services\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Dialogos.png\",\"contentUrl\":\"https:\\\/\\\/dialogos.ca\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Dialogos.png\",\"width\":340,\"height\":95,\"caption\":\"Di\u00e1logos Intercultural Services\"},\"image\":{\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DialogosInterculturalServices\",\"https:\\\/\\\/x.com\\\/DialogosTrans\",\"https:\\\/\\\/ca.linkedin.com\\\/pub\\\/martin-boyd\\\/3\\\/b7a\\\/b94\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dialogos.ca\\\/#\\\/schema\\\/person\\\/ee54b54565eded729000f79f6b337905\",\"name\":\"di\u00e1logos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g\",\"caption\":\"di\u00e1logos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chavela Vargas, una voz del m\u00e1s all\u00e1 - Di\u00e1logos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/","og_locale":"es_ES","og_type":"article","og_title":"Chavela Vargas, una voz del m\u00e1s all\u00e1 - Di\u00e1logos","og_description":"Martin Boyd Chavela Vargas, la cantante mexicana con voz incomparable que parece encarnar el esp\u00edritu mismo de la melancol\u00eda, nos dej\u00f3 el a\u00f1o pasado tras una carrera musical de m\u00e1s de 60 a\u00f1os que la convirti\u00f3 en una de las &hellip; Sigue leyendo &rarr;","og_url":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/","og_site_name":"Di\u00e1logos","article_publisher":"https:\/\/www.facebook.com\/DialogosInterculturalServices","article_published_time":"2013-12-06T19:30:25+00:00","article_modified_time":"2026-04-02T16:34:58+00:00","og_image":[{"width":386,"height":480,"url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas.jpeg","type":"image\/jpeg"}],"author":"di\u00e1logos","twitter_misc":{"Escrito por":"di\u00e1logos","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/#article","isPartOf":{"@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/"},"author":{"name":"di\u00e1logos","@id":"https:\/\/dialogos.ca\/#\/schema\/person\/ee54b54565eded729000f79f6b337905"},"headline":"Chavela Vargas, una voz del m\u00e1s all\u00e1","datePublished":"2013-12-06T19:30:25+00:00","dateModified":"2026-04-02T16:34:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/"},"wordCount":659,"commentCount":0,"publisher":{"@id":"https:\/\/dialogos.ca\/#organization"},"image":{"@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg","articleSection":["Cultura y sociedad"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/","url":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/","name":"Chavela Vargas, una voz del m\u00e1s all\u00e1 - Di\u00e1logos","isPartOf":{"@id":"https:\/\/dialogos.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/#primaryimage"},"image":{"@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg","datePublished":"2013-12-06T19:30:25+00:00","dateModified":"2026-04-02T16:34:58+00:00","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dialogos.ca\/es\/2013\/12\/chavela-vargas-una-voz-del-mas-alla\/#primaryimage","url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg","contentUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2013\/12\/Chavela-Vargas-241x300.jpeg"},{"@type":"WebSite","@id":"https:\/\/dialogos.ca\/#website","url":"https:\/\/dialogos.ca\/","name":"Di\u00e1logos","description":"Intercultural Services","publisher":{"@id":"https:\/\/dialogos.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dialogos.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/dialogos.ca\/#organization","name":"Di\u00e1logos Intercultural Services","url":"https:\/\/dialogos.ca\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/dialogos.ca\/#\/schema\/logo\/image\/","url":"https:\/\/dialogos.ca\/wp-content\/uploads\/2016\/12\/Dialogos.png","contentUrl":"https:\/\/dialogos.ca\/wp-content\/uploads\/2016\/12\/Dialogos.png","width":340,"height":95,"caption":"Di\u00e1logos Intercultural Services"},"image":{"@id":"https:\/\/dialogos.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DialogosInterculturalServices","https:\/\/x.com\/DialogosTrans","https:\/\/ca.linkedin.com\/pub\/martin-boyd\/3\/b7a\/b94"]},{"@type":"Person","@id":"https:\/\/dialogos.ca\/#\/schema\/person\/ee54b54565eded729000f79f6b337905","name":"di\u00e1logos","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b42a850ae7c35001147ce2c98fa9d77a882fbc4ca6f30fd5b8b36f32dc1dec56?s=96&d=mm&r=g","caption":"di\u00e1logos"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p45YGu-Kh","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/2869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/comments?post=2869"}],"version-history":[{"count":1,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/2869\/revisions"}],"predecessor-version":[{"id":5291,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/posts\/2869\/revisions\/5291"}],"wp:attachment":[{"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/media?parent=2869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/categories?post=2869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dialogos.ca\/es\/wp-json\/wp\/v2\/tags?post=2869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}